{"id":42,"count":1,"description":"","link":"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/","name":"Lauds Governor","slug":"lauds-governor","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lauds Governor Archives - Courage Times<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lauds Governor Archives - Courage Times\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/\" \/>\n<meta property=\"og:site_name\" content=\"Courage Times\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/tag\\\/lauds-governor\\\/\",\"url\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/tag\\\/lauds-governor\\\/\",\"name\":\"Lauds Governor Archives - Courage Times\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/tag\\\/lauds-governor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/tag\\\/lauds-governor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lauds Governor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/#website\",\"url\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/\",\"name\":\"Courage Times\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/#organization\",\"name\":\"Courage Times\",\"url\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/CTW_Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/CTW_Logo-1.png\",\"width\":1954,\"height\":1288,\"caption\":\"Courage Times\"},\"image\":{\"@id\":\"https:\\\/\\\/thecouragetimes.com\\\/inqxs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lauds Governor Archives - Courage Times","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/","og_locale":"en_US","og_type":"article","og_title":"Lauds Governor Archives - Courage Times","og_url":"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/","og_site_name":"Courage Times","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/","url":"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/","name":"Lauds Governor Archives - Courage Times","isPartOf":{"@id":"https:\/\/thecouragetimes.com\/inqxs\/#website"},"breadcrumb":{"@id":"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thecouragetimes.com\/inqxs\/tag\/lauds-governor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thecouragetimes.com\/inqxs\/"},{"@type":"ListItem","position":2,"name":"Lauds Governor"}]},{"@type":"WebSite","@id":"https:\/\/thecouragetimes.com\/inqxs\/#website","url":"https:\/\/thecouragetimes.com\/inqxs\/","name":"Courage Times","description":"","publisher":{"@id":"https:\/\/thecouragetimes.com\/inqxs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thecouragetimes.com\/inqxs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/thecouragetimes.com\/inqxs\/#organization","name":"Courage Times","url":"https:\/\/thecouragetimes.com\/inqxs\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thecouragetimes.com\/inqxs\/#\/schema\/logo\/image\/","url":"https:\/\/thecouragetimes.com\/inqxs\/wp-content\/uploads\/2024\/11\/CTW_Logo-1.png","contentUrl":"https:\/\/thecouragetimes.com\/inqxs\/wp-content\/uploads\/2024\/11\/CTW_Logo-1.png","width":1954,"height":1288,"caption":"Courage Times"},"image":{"@id":"https:\/\/thecouragetimes.com\/inqxs\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/thecouragetimes.com\/inqxs\/wp-json\/wp\/v2\/tags\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thecouragetimes.com\/inqxs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thecouragetimes.com\/inqxs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thecouragetimes.com\/inqxs\/wp-json\/wp\/v2\/posts?tags=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}